{"id":1604,"count":36,"description":"","link":"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/","name":"Madam Stoltz","slug":"madam-stoltz","taxonomy":"product_brand","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Madam Stoltz Arkiv | Himmerli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madam Stoltz Arkiv\" \/>\n<meta property=\"og:url\" content=\"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/\" \/>\n<meta property=\"og:site_name\" content=\"Himmerli\" \/>\n<meta property=\"og:image\" content=\"https:\/\/himmerli.com\/wp-content\/uploads\/HIMMERLI-black-on-beige-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/varem\u00e6rke\\\/madam-stoltz\\\/\",\"url\":\"https:\\\/\\\/himmerli.com\\\/en\\\/varem\u00e6rke\\\/madam-stoltz\\\/\",\"name\":\"Madam Stoltz Arkiv | Himmerli\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/himmerli.com\\\/en\\\/\",\"name\":\"himmerli.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/himmerli.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#organization\",\"name\":\"Himmerli\",\"url\":\"https:\\\/\\\/himmerli.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/himmerli.com\\\/wp-content\\\/uploads\\\/HIMMERLI-beige.svg\",\"contentUrl\":\"https:\\\/\\\/himmerli.com\\\/wp-content\\\/uploads\\\/HIMMERLI-beige.svg\",\"caption\":\"Himmerli\"},\"image\":{\"@id\":\"https:\\\/\\\/himmerli.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100087930706798\",\"https:\\\/\\\/www.instagram.com\\\/himmerli\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Madam Stoltz Arkiv | Himmerli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/","og_locale":"en_US","og_type":"article","og_title":"Madam Stoltz Arkiv","og_url":"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/","og_site_name":"Himmerli","og_image":[{"width":2048,"height":2048,"url":"https:\/\/himmerli.com\/wp-content\/uploads\/HIMMERLI-black-on-beige-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/","url":"https:\/\/himmerli.com\/en\/varem\u00e6rke\/madam-stoltz\/","name":"Madam Stoltz Arkiv | Himmerli","isPartOf":{"@id":"https:\/\/himmerli.com\/en\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/himmerli.com\/en\/#website","url":"https:\/\/himmerli.com\/en\/","name":"himmerli.com","description":"","publisher":{"@id":"https:\/\/himmerli.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/himmerli.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/himmerli.com\/en\/#organization","name":"Himmerli","url":"https:\/\/himmerli.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/himmerli.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/himmerli.com\/wp-content\/uploads\/HIMMERLI-beige.svg","contentUrl":"https:\/\/himmerli.com\/wp-content\/uploads\/HIMMERLI-beige.svg","caption":"Himmerli"},"image":{"@id":"https:\/\/himmerli.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100087930706798","https:\/\/www.instagram.com\/himmerli\/"]}]}},"_links":{"self":[{"href":"https:\/\/himmerli.com\/en\/wp-json\/wp\/v2\/product_brand\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/himmerli.com\/en\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/himmerli.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"wp:post_type":[{"href":"https:\/\/himmerli.com\/en\/wp-json\/wp\/v2\/product?product_brand=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}